{"id":82895,"date":"2021-12-29T08:51:43","date_gmt":"2021-12-29T08:51:43","guid":{"rendered":"https:\/\/websitedesigns.com.au\/elankanew\/?p=82895"},"modified":"2021-12-29T08:51:43","modified_gmt":"2021-12-29T08:51:43","slug":"when-a-child-is-born-st-peters-college-christmas-carols-2021","status":"publish","type":"post","link":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/","title":{"rendered":"When A Child is Born &#8211; St.Peter&#8217;s College Christmas Carols 2021"},"content":{"rendered":"<h1 style=\"text-align: center;\"><strong><span style=\"color: #000080; font-size: 24px;\">When A Child is Born &#8211; St.Peter&#8217;s College Christmas Carols 2021<\/span><\/strong><\/h1>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/qPWpY63DJ6o\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>When A Child is Born &#8211; St.Peter&#8217;s College Christmas Carols 2021 &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":82896,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[20],"tags":[40541],"class_list":{"0":"post-82895","1":"post","2":"type-post","3":"status-publish","4":"format-aside","5":"has-post-thumbnail","7":"category-articles","8":"tag-st-peters-college-christmas-carols-2021","9":"post_format-post-format-aside"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>When A Child is Born - St.Peter&#039;s College Christmas Carols 2021 - eLanka<\/title>\n<meta name=\"description\" content=\"When A Child is Born - St.Peter&#039;s College Christmas Carols 2021\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"When A Child is Born - St.Peter&#039;s College Christmas Carols 2021\" \/>\n<meta property=\"og:description\" content=\"When A Child is Born - St.Peter&#039;s College Christmas Carols 2021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"eLanka\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eLanka.com.au\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-29T08:51:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"204\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"eLanka admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eLanka admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/\"},\"author\":{\"name\":\"eLanka admin\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/person\/f6e635b74ab35ef88a68a9973cacc5bd\"},\"headline\":\"When A Child is Born &#8211; St.Peter&#8217;s College Christmas Carols 2021\",\"datePublished\":\"2021-12-29T08:51:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/\"},\"wordCount\":25,\"publisher\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#organization\"},\"image\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png\",\"keywords\":[\"St.Peter's College Christmas Carols 2021\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/\",\"name\":\"When A Child is Born - St.Peter's College Christmas Carols 2021 - eLanka\",\"isPartOf\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png\",\"datePublished\":\"2021-12-29T08:51:43+00:00\",\"description\":\"When A Child is Born - St.Peter's College Christmas Carols 2021\",\"breadcrumb\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png\",\"contentUrl\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png\",\"width\":600,\"height\":204,\"caption\":\"St.Peter's College Christmas Carols 2021\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/websitedesigns.com.au\/elankanew\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/websitedesigns.com.au\/elankanew\/category\/articles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"When A Child is Born &#8211; St.Peter&#8217;s College Christmas Carols 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#website\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/\",\"name\":\"eLanka\",\"description\":\"eLanka - Sri lanka events in Australia\",\"publisher\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/websitedesigns.com.au\/elankanew\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#organization\",\"name\":\"eLanka\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg\",\"contentUrl\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg\",\"width\":192,\"height\":82,\"caption\":\"eLanka\"},\"image\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eLanka.com.au\/\",\"https:\/\/www.linkedin.com\/in\/elanka\/\",\"https:\/\/www.youtube.com\/user\/SriLankanDownUnder\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/person\/f6e635b74ab35ef88a68a9973cacc5bd\",\"name\":\"eLanka admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e0d346a7f97b80e861cdeafe7b7de523b59f5060666f1a5da8369457bf9b6c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e0d346a7f97b80e861cdeafe7b7de523b59f5060666f1a5da8369457bf9b6c3?s=96&d=mm&r=g\",\"caption\":\"eLanka admin\"},\"sameAs\":[\"https:\/\/websitedesigns.com.au\/elankanew\"],\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/author\/elanka\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"When A Child is Born - St.Peter's College Christmas Carols 2021 - eLanka","description":"When A Child is Born - St.Peter's College Christmas Carols 2021","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"When A Child is Born - St.Peter's College Christmas Carols 2021","og_description":"When A Child is Born - St.Peter's College Christmas Carols 2021","og_url":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/","og_site_name":"eLanka","article_publisher":"https:\/\/www.facebook.com\/eLanka.com.au\/","article_published_time":"2021-12-29T08:51:43+00:00","og_image":[{"width":600,"height":204,"url":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png","type":"image\/png"}],"author":"eLanka admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eLanka admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#article","isPartOf":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/"},"author":{"name":"eLanka admin","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/person\/f6e635b74ab35ef88a68a9973cacc5bd"},"headline":"When A Child is Born &#8211; St.Peter&#8217;s College Christmas Carols 2021","datePublished":"2021-12-29T08:51:43+00:00","mainEntityOfPage":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/"},"wordCount":25,"publisher":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/#organization"},"image":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png","keywords":["St.Peter's College Christmas Carols 2021"],"articleSection":["Articles"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/","url":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/","name":"When A Child is Born - St.Peter's College Christmas Carols 2021 - eLanka","isPartOf":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/#website"},"primaryImageOfPage":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage"},"image":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png","datePublished":"2021-12-29T08:51:43+00:00","description":"When A Child is Born - St.Peter's College Christmas Carols 2021","breadcrumb":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#primaryimage","url":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png","contentUrl":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2021\/12\/stpeters-college-colombo4-e1640767872537.png","width":600,"height":204,"caption":"St.Peter's College Christmas Carols 2021"},{"@type":"BreadcrumbList","@id":"https:\/\/websitedesigns.com.au\/elankanew\/when-a-child-is-born-st-peters-college-christmas-carols-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/websitedesigns.com.au\/elankanew\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/websitedesigns.com.au\/elankanew\/category\/articles\/"},{"@type":"ListItem","position":3,"name":"When A Child is Born &#8211; St.Peter&#8217;s College Christmas Carols 2021"}]},{"@type":"WebSite","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#website","url":"https:\/\/websitedesigns.com.au\/elankanew\/","name":"eLanka","description":"eLanka - Sri lanka events in Australia","publisher":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/websitedesigns.com.au\/elankanew\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#organization","name":"eLanka","url":"https:\/\/websitedesigns.com.au\/elankanew\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/","url":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg","contentUrl":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg","width":192,"height":82,"caption":"eLanka"},"image":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eLanka.com.au\/","https:\/\/www.linkedin.com\/in\/elanka\/","https:\/\/www.youtube.com\/user\/SriLankanDownUnder"]},{"@type":"Person","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/person\/f6e635b74ab35ef88a68a9973cacc5bd","name":"eLanka admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2e0d346a7f97b80e861cdeafe7b7de523b59f5060666f1a5da8369457bf9b6c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e0d346a7f97b80e861cdeafe7b7de523b59f5060666f1a5da8369457bf9b6c3?s=96&d=mm&r=g","caption":"eLanka admin"},"sameAs":["https:\/\/websitedesigns.com.au\/elankanew"],"url":"https:\/\/websitedesigns.com.au\/elankanew\/author\/elanka\/"}]}},"_links":{"self":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/posts\/82895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/comments?post=82895"}],"version-history":[{"count":1,"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/posts\/82895\/revisions"}],"predecessor-version":[{"id":82897,"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/posts\/82895\/revisions\/82897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/media\/82896"}],"wp:attachment":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/media?parent=82895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/categories?post=82895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/tags?post=82895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}