{"id":668,"count":1,"description":"","link":"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/","name":"Live longer","slug":"live-longer","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Live longer Archives - eLanka<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Live longer Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/\" \/>\n<meta property=\"og:site_name\" content=\"eLanka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/\",\"name\":\"Live longer Archives - eLanka\",\"isPartOf\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/websitedesigns.com.au\/elankanew\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Live longer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#website\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/\",\"name\":\"eLanka\",\"description\":\"eLanka - Sri lanka events in Australia\",\"publisher\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/websitedesigns.com.au\/elankanew\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#organization\",\"name\":\"eLanka\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg\",\"contentUrl\":\"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg\",\"width\":192,\"height\":82,\"caption\":\"eLanka\"},\"image\":{\"@id\":\"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eLanka.com.au\/\",\"https:\/\/www.linkedin.com\/in\/elanka\/\",\"https:\/\/www.youtube.com\/user\/SriLankanDownUnder\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Live longer Archives - eLanka","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Live longer Archives","og_url":"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/","og_site_name":"eLanka","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/","url":"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/","name":"Live longer Archives - eLanka","isPartOf":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/#website"},"breadcrumb":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/websitedesigns.com.au\/elankanew\/tag\/live-longer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/websitedesigns.com.au\/elankanew\/"},{"@type":"ListItem","position":2,"name":"Live longer"}]},{"@type":"WebSite","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#website","url":"https:\/\/websitedesigns.com.au\/elankanew\/","name":"eLanka","description":"eLanka - Sri lanka events in Australia","publisher":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/websitedesigns.com.au\/elankanew\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#organization","name":"eLanka","url":"https:\/\/websitedesigns.com.au\/elankanew\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/","url":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg","contentUrl":"https:\/\/websitedesigns.com.au\/elankanew\/wp-content\/uploads\/2020\/03\/elanka-logo.jpg","width":192,"height":82,"caption":"eLanka"},"image":{"@id":"https:\/\/websitedesigns.com.au\/elankanew\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eLanka.com.au\/","https:\/\/www.linkedin.com\/in\/elanka\/","https:\/\/www.youtube.com\/user\/SriLankanDownUnder"]}]}},"_links":{"self":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/tags\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/websitedesigns.com.au\/elankanew\/wp-json\/wp\/v2\/posts?tags=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}